{"id":13,"date":"2003-05-05T00:00:00","date_gmt":"2003-05-05T00:00:00","guid":{"rendered":"http:\/\/blog.ensci.com\/enjeuxusages\/2003\/05\/05\/plan-succinct\/"},"modified":"2010-11-10T08:44:40","modified_gmt":"2010-11-10T08:44:40","slug":"plan-succinct","status":"publish","type":"post","link":"https:\/\/blog.ensci.com\/enjeuxusages\/2003\/05\/05\/plan-succinct\/","title":{"rendered":"Plan succinct"},"content":{"rendered":"<p>L&rsquo;homme porteur d&rsquo;objets communicants.<br \/>\nL&rsquo;homme objet communicant ?<\/p>\n<p>Des hommes et des ondes \/ des ondes et des hommes<\/p>\n<p>Pour qui ? pour quoi ? pour quel avenir ?<br \/>\nPourquoi ? pour quel avenir ?<br \/>\nPhilo\/ eco\/ socio\/<\/p>\n<p>Intro :<br \/>\nQu&rsquo;est qu&rsquo;un objet communicant ?<br \/>\nObjet communicant mais communicant sous quelle forme ?<br \/>\nCommunication \/ communiquer<br \/>\nDef dico robert : Le fait d&rsquo;\u00e9tablir une relation avec quelqu&rsquo;un, quelque chose, de partager.<br \/>\nSuppose un \u00e9change, un retour d&rsquo;information, que ce soit d&rsquo;un homme ou d&rsquo;un objet.<br \/>\nL&rsquo;homme\/son corps\/la technologie<br \/>\nCorps support de technologie\/<br \/>\nOn communique sans le savoir<br \/>\nLangage des signes<\/p>\n<p>I constats<br \/>\nCommuniquer avec qui ? avec quoi ?<br \/>\nDans domaines : Domestique, loisir, m\u00e9dical<br \/>\n3 types :<br \/>\n.Objets port\u00e9s momentan\u00e9ment sur soi. Objets prolongements de l&rsquo;homme.<br \/>\nQuels types d&rsquo;objets \/ quels domaines ?<br \/>\nTel portable \/ smart phone<br \/>\nPda<br \/>\nOrdinateur portable<br \/>\nTelecommande<br \/>\nGps<br \/>\nTalkie-walkie<br \/>\nCarte bleue<br \/>\nClefs<\/p>\n<p>.Objets port\u00e9s continuellement sur soi. Objets implant\u00e9s<br \/>\nQuels types d&rsquo;objets \/ quels domaines ?<br \/>\nObjet interne<br \/>\nContinuellement sur soi<br \/>\nImplant\u00e9<br \/>\nM\u00e9dical : diab\u00e8te \/ appareil \u00e0 insuline \/ Pacemaker \/ implant dentaire \/ oculaire \/ contraceptif<br \/>\nMilitaire<\/p>\n<p>.Finalement l&rsquo;homme lui m\u00eame :<br \/>\nReconnaissance digitale\/ visuelle\/ vocale\/ du visage<\/p>\n<p>II projection dans l&rsquo;avenir et cons\u00e9quence pour l&rsquo;homme<br \/>\nInt\u00e9r\u00eats partag\u00e9s ? pour qui ? pour quels usages ?<br \/>\nInt\u00e9r\u00eats pour industriels ?<br \/>\nInt\u00e9r\u00eats pour les scientifiques ?<br \/>\nInt\u00e9r\u00eats d&rsquo;un gouvernement ?<br \/>\nInt\u00e9r\u00eats pour l&rsquo;usager ?<\/p>\n<p>Ex :<br \/>\nBadge. Ou reconnaissance digitale.<br \/>\nUne partie du corps devient objet et il y a un retour &#8211; machine<br \/>\nCe sont les particularit\u00e9s de l&rsquo;homme qui le font devenir objet. L&rsquo;homme garde alors son int\u00e9grit\u00e9. Mais si implantation, attention risque de prise de contr\u00f4le de l&rsquo;homme -> l&rsquo;homme subit, devient soumis.<\/p>\n<p>Application de demain\/ domestique<br \/>\nScientifique qui s&rsquo;implante une puce dans le bras<\/p>\n<p>Efficacit\u00e9 \/ risque ? (contr\u00f4le de la personne \/ suivie \/ vie priv\u00e9e)<br \/>\nEthique : atteinte au niveau de l&rsquo;homme (+intrusion sous la peau)<br \/>\nAtteinte au niveau de l&rsquo;humanit\u00e9\u2026 les m\u00eanes d\u00e9passent les g\u00eanes\u2026 l&rsquo;homme lutte contre l&rsquo;\u00e9volution  de l&rsquo;esp\u00e8ce.<\/p>\n<p>Conclusion<br \/>\nA l&rsquo;homme de d\u00e9cider<br \/>\nQuel homme veut on devenir ?<br \/>\nL&rsquo;homme bionique<br \/>\nEternelle ?<br \/>\nDiriger d&rsquo;autres hommes<br \/>\nObliger \u00e0 faire des gestes<\/p>\n<p>Finalement 2 sc\u00e9narios :<br \/>\nUn rose<br \/>\nUn noir  o\u00f9 il y aura homme qui ont technique technologie connaissances<br \/>\nArgent.<\/p>\n<p>Et dessous hommes lobotomis\u00e9s<\/p>\n<p>Metropolis fritz lang<br \/>\nL&rsquo;ile du docteur moreau<br \/>\nSchuiten<br \/>\nShadock<\/p>\n<p>Moi j&rsquo;espere<br \/>\nJe pense<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;homme porteur d&rsquo;objets communicants. L&rsquo;homme objet communicant ? Des hommes et des ondes \/ des ondes et des hommes Pour qui ? pour quoi ? pour quel avenir ? Pourquoi ? pour quel avenir ? Philo\/ eco\/ socio\/ Intro : &hellip; <a href=\"https:\/\/blog.ensci.com\/enjeuxusages\/2003\/05\/05\/plan-succinct\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":108,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[3,6],"tags":[],"class_list":["post-13","post","type-post","status-publish","format-standard","hentry","category-enjeux-et-usages-des-tic-fevrier-juin-2003","category-lhomme-porteur-dobjets-communicants"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/blog.ensci.com\/enjeuxusages\/wp-json\/wp\/v2\/posts\/13","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.ensci.com\/enjeuxusages\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.ensci.com\/enjeuxusages\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.ensci.com\/enjeuxusages\/wp-json\/wp\/v2\/users\/108"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.ensci.com\/enjeuxusages\/wp-json\/wp\/v2\/comments?post=13"}],"version-history":[{"count":2,"href":"https:\/\/blog.ensci.com\/enjeuxusages\/wp-json\/wp\/v2\/posts\/13\/revisions"}],"predecessor-version":[{"id":162,"href":"https:\/\/blog.ensci.com\/enjeuxusages\/wp-json\/wp\/v2\/posts\/13\/revisions\/162"}],"wp:attachment":[{"href":"https:\/\/blog.ensci.com\/enjeuxusages\/wp-json\/wp\/v2\/media?parent=13"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.ensci.com\/enjeuxusages\/wp-json\/wp\/v2\/categories?post=13"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.ensci.com\/enjeuxusages\/wp-json\/wp\/v2\/tags?post=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}